{"id":60045,"date":"2024-07-08T09:00:34","date_gmt":"2024-07-08T07:00:34","guid":{"rendered":"https:\/\/solarchitecture.ch\/malley-phare\/"},"modified":"2025-02-18T10:45:30","modified_gmt":"2025-02-18T09:45:30","slug":"malley-phare","status":"publish","type":"post","link":"https:\/\/solarchitecture.ch\/it\/malley-phare\/","title":{"rendered":"Malley Phare"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column offset=&#8221;vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]<\/p>\n<p>[vc_acf field_group=&#8221;30126&#8243; field_from_30126=&#8221;field_5c079de146ee1&#8243;]<\/p>\n<p>[\/vc_column][\/vc_row][vc_row][vc_column]<\/p>\n<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"100\" data-normal_resolution=\"1024\" data-normal_size=\"100\" data-tablet_resolution=\"800\" data-tablet_size=\"50\" data-mobile_resolution=\"480\" data-mobile_size=\"50\" style=\"height: 100px;\"><\/div>\n<p>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;3\/4&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1548941680917{border-right-width: 1px !important;padding-right: 25px !important;padding-left: 25px !important;border-right-color: #000000 !important;border-right-style: solid !important;}&#8221; responsive_styles=&#8221;border_right_mobile:0&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_01 cr-animate-gen dfd-heading-6a97c75a27438 dfd-enable-resposive-headings\" id=\"dfd-heading-6a97c75a27438\" data-animate-type = \"transition.slideLeftIn\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><div class=\"widget-title dfd-title block-title\" style=\"font-family:Montserrat; font-weight:700; font-style:normal; font-size: 35px; color: #000000 !important; line-height: 45px; letter-spacing: 0px; \"><\/p>\n<p>Malley Phare \u2013 La fase di costruzione<\/p>\n<p><\/div><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97c75a27438.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}@media (max-width: 1279px) and (min-width: 1024px){.dfd-heading-6a97c75a27438 .dfd-title{font-size: 40px !important;letter-spacing: 0px !important;line-height: 45px !important;}}@media (max-width: 1023px) and (min-width: 800px){.dfd-heading-6a97c75a27438 .dfd-title{font-size: 35px !important;letter-spacing: 0px !important;line-height: 40px !important;}}@media (max-width: 799px){.dfd-heading-6a97c75a27438 .dfd-title{font-size: 30px !important;letter-spacing: 0px !important;line-height: 35px !important;}}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[vc_column_text css=&#8221;.vc_custom_1718630926770{padding-bottom: 30px !important;}&#8221;]<\/p>\n<p>8 luglio 2024<\/p>\n<p>[\/vc_column_text][vc_single_image image=&#8221;60038&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][vc_column_text css=&#8221;.vc_custom_1718630979539{padding-top: 10px !important;padding-bottom: 10px !important;}&#8221;]<\/p>\n<h3 style=\"text-align: left;\" data-mce-style=\"text-align: left;\">La realizzazione \u00e8 iniziata nel 2022 e il suo completamento \u00e8 previsto per il 2025. Fonte: CCHE.<\/h3>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1726325730474{padding-top: 25px !important;}&#8221;]<\/p>\n<p><em>Si tratta della prima torre in legno con facciata fotovoltaica attiva della Svizzera romanda.<\/em><\/p>\n<p><\/p>\n<p>Il quartiere del Viadotto Malley \u00e8 contrassegnato dal marchio Area 2000 watt e il nuovo ampliamento di Malley Phare sar\u00e0 conforme al marchio Minergie-Eco e ai requisiti della norma SIA 2040. Il progetto \u00e8 stato realizzato da Perspectives Construction, in consorzio con JPF Ducret.<\/p>\n<p><\/p>\n<p>Il Malley Phare, opera architettonica emblematica con un&#8217;altezza di 60 metri, \u00e8 un oggetto esemplare dal punto di vista energetico e socio-culturale. L&#8217;utilizzo di legno proveniente quasi esclusivamente da fonti autoctone permette di rispondere a diverse sfide: applicazione dei principi della societ\u00e0 2000 Watts, aumento delle prestazioni energetiche, sviluppo sostenibile, riduzione della durata del cantiere, leggerezza della struttura.<\/p>\n<p><\/p>\n<p>Il nuovo edificio \u00e8 composto da 14 piani divisi da 3 piani tipici. Questa organizzazione crea un design di facciata composto da fessure, intagli e logge. Diversi spazi comuni sono a disposizione degli abitanti: sale \u201cjokers\u201d nonch\u00e9 locali di coworking e home office (a doppia altezza) per favorire il telelavoro e rispondere a un&#8217;esigenza crescente e attuale.<\/p>\n<p><\/p>\n<p>Una delle caratteristiche pi\u00f9 significative di Malley Phare \u00e8 il suo impegno per la sostenibilit\u00e0, esemplificato dall&#8217;ampia installazione fotovoltaica sulle sue facciate. Questo impianto non \u00e8 solo un&#8217;aggiunta, ma una componente fondamentale del progetto e della strategia energetica dell&#8217;edificio.<\/p>\n<p><\/p>\n<p>Di seguito viene presentata un&#8217;analisi approfondita del sistema fotovoltaico e dei suoi vantaggi:<\/p>\n<p><\/p>\n<p><strong>Integrazione architettonica<\/strong>: i moduli fotovoltaici sono perfettamente integrati nelle facciate dell&#8217;edificio, unendo funzionalit\u00e0 ed estetica. Questo design fa s\u00ec che l&#8217;impianto fotovoltaico non tolga nulla all&#8217;aspetto elegante e moderno dell&#8217;edificio, ma anzi lo valorizzi.<\/p>\n<p><\/p>\n<p><strong>Efficienza energetica<\/strong>: l&#8217;impianto fotovoltaico \u00e8 progettato per sfruttare al massimo la luce solare, convertendola in energia rinnovabile. Ci\u00f2 contribuisce in modo significativo all&#8217;efficienza energetica complessiva dell&#8217;edificio, riducendo la dipendenza da fonti energetiche non rinnovabili e diminuendo le emissioni di CO2.<\/p>\n<p><\/p>\n<p><strong>Abitare la citt\u00e0 in modo sostenibile<\/strong>: incorporando fonti di energia rinnovabili, Malley Phare promuove un abitare urbano sostenibile. L&#8217;elettricit\u00e0 generata dai moduli fotovoltaici pu\u00f2 alimentare diverse operazioni dell&#8217;edificio, dall&#8217;illuminazione al riscaldamento, fino all&#8217;alimentazione delle aree comuni, riducendo cos\u00ec l&#8217;impronta ambientale complessiva.<\/p>\n<p><\/p>\n<p><strong>Tecnologia innovativa<\/strong>: l&#8217;impianto fotovoltaico utilizza le pi\u00f9 recenti tecnologie solari, garantendo un&#8217;elevata efficienza e durabilit\u00e0.<\/p>\n<p><\/p>\n<p><strong>Vantaggi economici<\/strong>: l&#8217;uso dell&#8217;energia solare riduce i costi operativi diminuendo le bollette energetiche dell&#8217;edificio. Inoltre, il progetto beneficia di vari incentivi e sussidi disponibili per i progetti che utilizzano le energie rinnovabili, rendendolo una soluzione economicamente vantaggiosa a lungo termine.<\/p>\n<p><\/p>\n<p><strong>Impatto ambientale<\/strong>: i benefici ambientali sono notevoli, in quanto l&#8217;uso di moduli fotovoltaici riduce significativamente le emissioni di gas serra. Malley Phare funge da modello per l&#8217;edilizia sostenibile, dimostrando come gli edifici urbani possano contribuire alla mitigazione dei cambiamenti climatici.<\/p>\n<p><\/p>\n<p>Il Malley Phare \u00e8 pi\u00f9 di un semplice edificio di grandi dimensioni: \u00e8 un faro per lo sviluppo sostenibile di Losanna. L&#8217;uso innovativo di moduli fotovoltaici integrati sulle sue facciate costituisce un precedente per i progetti urbani futuri, evidenziando il potenziale dell&#8217;integrazione di soluzioni di energia rinnovabile nell&#8217;architettura moderna. Mentre le citt\u00e0 di tutto il mondo sono alle prese con le sfide del cambiamento climatico e dell&#8217;urbanizzazione, Malley Phare si distingue come un progetto esemplare che armonizza il progresso tecnologico con la gestione dell&#8217;ambiente.<\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/4&#8243; dfd_column_responsive_enable=&#8221;dfd-column-responsive-enable&#8221; css=&#8221;.vc_custom_1548941751542{padding-right: 25px !important;padding-left: 25px !important;}&#8221; responsive_styles=&#8221;padding_top_mobile:80&#8243;]<div class=\"dfd-heading-shortcode\"><div class=\"dfd-heading-module-wrap  text-left style_01 dfd-heading-6a97c75a27507 dfd-enable-resposive-headings\" id=\"dfd-heading-6a97c75a27507\" ><div class=\"inline-block\"><div class=\"dfd-heading-module\"><div class=\"widget-title dfd-title block-title\" style=\"font-size: 25px; font-family: MontserratBold; color: #000000 !important; line-height: 32px; letter-spacing: 0px; \"><\/p>\n<p>Vedi anche<\/p>\n<p><\/div><\/div><\/div><\/div><script type=\"text\/javascript\">\r\n\t\t\t\t\t\t\t\t\t(function($) {\r\n\t\t\t\t\t\t\t\t\t\t$(\"head\").append(\"<style>.dfd-heading-6a97c75a27507 .dfd-heading-module .widget-title {margin-bottom:15px;}.dfd-heading-6a97c75a27507.dfd-heading-module-wrap .dfd-heading-module .dfd-heading-delimiter {margin-top:10px;margin-bottom:10px;}<\/style>\");\r\n\t\t\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t\t\t\t\t\t<\/script><\/div>[vc_row_inner][vc_column_inner css=&#8221;.vc_custom_1583843692171{padding-top: 25px !important;}&#8221; col_inner_shadow=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221; col_inner_shadow_hover=&#8221;box_shadow_enable:disable|shadow_horizontal:0|shadow_vertical:15|shadow_blur:50|shadow_spread:0|box_shadow_color:rgba(0%2C0%2C0%2C0.35)&#8221;]<div id=\"idinfobox6a97c75a27578\" class=\"dfd-info-box clearfix style-01 layout-04  idinfobox6a97c75a27578 cr-animate-gen\" data-animate-item=\".dfd-animate-container\" data-animate-type = \"transition.slideUpIn\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" style=\"border-radius:px;font-size:65px;\"><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/CCHE-logo-130x130.png\" alt=\"Image icon\" style=\"width: 65px;opacity: 1;\" \/><\/div><\/div><div class=\"content-wrap ovh\"><div class=\"info-box-title feature-title\" style=\"font-size: 14px; color: #000000 !important; line-height: 20px; \">CCHE<\/div><div class=\"info-box-subtitle subtitle\" style=\"font-size: 14px; color: #000000 !important; line-height: 20px; font-style:italic; \">Visita il sito web (EN, FR, DE)<\/div><div class=\"description\" style=\"\"><\/div><\/div><a href=\"https:\/\/cche.com\/en\/Projects\/malley-phare\/\"  target=\"_blank\" class=\"full-box-link\"><\/a><\/div><\/div><div id=\"idinfobox6a97c75a27917\" class=\"dfd-info-box clearfix style-01 layout-04  idinfobox6a97c75a27917 cr-animate-gen\" data-animate-item=\".dfd-animate-container\" data-animate-type = \"transition.slideUpIn\" ><div class=\"dfd-animate-container\"><div class=\"icon-wrapper\"><div class=\"module-icon\" style=\"border-radius:px;font-size:65px;\"><div class=\"hover-layer\" ><\/div><img decoding=\"async\" src=\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_logo-130x130.jpg\" alt=\"Image icon\" style=\"width: 65px;opacity: 1;\" \/><\/div><\/div><div class=\"content-wrap ovh\"><div class=\"info-box-title feature-title\" style=\"font-size: 14px; color: #000000 !important; line-height: 20px; \">Malley Phare<\/div><div class=\"info-box-subtitle subtitle\" style=\"font-size: 14px; color: #000000 !important; line-height: 20px; font-style:italic; \">Visita il sito web (FR)<\/div><div class=\"description\" style=\"\"><\/div><\/div><a href=\"https:\/\/malleyphare.ch\/\"  target=\"_blank\" class=\"full-box-link\"><\/a><\/div><\/div>[\/vc_column_inner][\/vc_row_inner]<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"80\" data-normal_resolution=\"1024\" data-normal_size=\"80\" data-tablet_resolution=\"800\" data-tablet_size=\"80\" data-mobile_resolution=\"480\" data-mobile_size=\"80\" style=\"height: 80px;\"><\/div><div class=\"dfd-shar-module-cover\"><div class=\"dfd-new-share-module  text-left style-6 horizontal   \" ><div class=\"module module-entry-share\" id=\"dfd_share_6a97c75a27be0\"><ul class=\"module-entry-share-links-list rrssb-buttons\" data-directory=\"https:\/\/solarchitecture.ch\/wp-content\/themes\/dfd-ronneby\"><li class=\"rrssb-facebook\"><a class=\"module-entry-share-link-facebook feature-title\" data-title=\"Solarchitecture\" data-url=\"https:\/\/solarchitecture.ch\" data-media=\"\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/solarchitecture.ch\"  style=\"border-radius: 1px; font-size: 14px; \"><span class=\"dfd-share-icon\" style=\"width: 30px; height: 30px; line-height: 30px;\"><\/span><\/a><\/li><li class=\"rrssb-linkedin\"><a class=\"module-entry-share-link-linkedin feature-title\" data-title=\"Solarchitecture\" data-url=\"https:\/\/solarchitecture.ch\" data-media=\"\" href=\"http:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https:\/\/solarchitecture.ch\"  style=\"border-radius: 1px; font-size: 14px; \"><span class=\"dfd-share-icon\" style=\"width: 30px; height: 30px; line-height: 30px;\"><\/span><\/a><\/li><li class=\"rrssb-pinterest\"><a class=\"module-entry-share-link-pinterest feature-title\" data-title=\"Solarchitecture\" data-url=\"https:\/\/solarchitecture.ch\" data-media=\"\" href=\"http:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/solarchitecture.ch&#038;image_url=https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg\"  style=\"border-radius: 1px; font-size: 14px; \"><span class=\"dfd-share-icon\" style=\"width: 30px; height: 30px; line-height: 30px;\"><\/span><\/a><\/li><\/ul><\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\t(function ($) {\r\n\t\t\t\t\t\"use strict\";\r\n\t\t\t\t\t$(document).ready(function () {\r\n\t\t\t\t\t\tvar $share_container = $('#dfd_share_6a97c75a27be0 .module-entry-share-links-list li');\r\n\t\t\t\t\t\tvar parent = $share_container.parent().parent().parent();\r\n\t\t\t\t\t\tif ($share_container.length > 0) {\r\n\t\t\t\t\t\t\tvar scrollbarWidth;\r\n\t\t\t\t\t\t\tvar div = document.createElement('div');\r\n\t\t\t\t\t\t\tdiv.style.overflowY = 'scroll';\r\n\t\t\t\t\t\t\tdiv.style.width = '50px';\r\n\t\t\t\t\t\t\tdiv.style.height = '50px';\r\n\t\t\t\t\t\t\tdiv.style.visibility = 'hidden';\r\n\t\t\t\t\t\t\tdocument.body.appendChild(div);\r\n\t\t\t\t\t\t\tscrollbarWidth = div.offsetWidth - div.clientWidth;\r\n\t\t\t\t\t\t\tdocument.body.removeChild(div);\r\n\t\t\t\t\t\t\tvar setShareWidth = function () {\r\n\t\t\t\t\t\t\t\tif (($(window).width() + scrollbarWidth) >= 800) {\r\n\t\t\t\t\t\t\t\t\tif (parent.hasClass(\"style-6\") || parent.hasClass(\"style-7\") || parent.hasClass(\"vertical\")) {\r\n\t\t\t\t\t\t\t\t\t\t$share_container.width('auto');\r\n\t\t\t\t\t\t\t\t\t} else {\r\n\t\t\t\t\t\t\t\t\t\t$share_container.dfdEqWidth();\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t} else {\r\n\t\t\t\t\t\t\t\t\tif (parent.hasClass(\"style-6\") || parent.hasClass(\"style-7\") || parent.hasClass(\"vertical\")) {\r\n\t\t\t\t\t\t\t\t\t\t$share_container.width('auto');\r\n\t\t\t\t\t\t\t\t\t} else {\r\n\t\t\t\t\t\t\t\t\t\t$share_container.width('100%');\r\n\t\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t\t};\r\n\t\t\t\t\t\t\tsetShareWidth();\r\n\t\t\t\t\t\t\t$(window).resize(setShareWidth);\r\n\t\t\t\t\t\t}\r\n\t\t\t\t\t});\r\n\t\t\t\t\t\t\t\t\t$('head').append('<style type=\"text\/css\">.dfd-new-share-module.style-6 #dfd_share_6a97c75a27be0 ul li a {border-style: solid;border-width: 1px;border-color: #000000;background: #ffffff;color: #000000;}<\/style>');\r\n\t\t\t\t\t\t\t})(jQuery);\r\n\t\t\t<\/script>\r\n\r\n\t\t\t<\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<\/p>\n<div class=\"dfd-spacer-module\"  data-units=\"px\" data-wide_resolution=\"1280\" data-wide_size=\"100\" data-normal_resolution=\"1024\" data-normal_size=\"100\" data-tablet_resolution=\"800\" data-tablet_size=\"100\" data-mobile_resolution=\"480\" data-mobile_size=\"100\" style=\"height: 100px;\"><\/div>\n<p>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Si tratta del primo edificio con struttura in legno della Svizzera francese con una facciata fotovoltaica attiva. Il quartiere del Viadotto di Malley \u00e8 contrassegnato dal marchio &#8220;Sito 2000 watt&#8221; e la nuova estensione di Malley Phare soddisfer\u00e0&#8230;<\/p>\n","protected":false},"author":2021,"featured_media":60033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[458],"tags":[],"class_list":["post-60045","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Malley Phare - Solarchitecture<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solarchitecture.ch\/it\/malley-phare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Malley Phare - Solarchitecture\" \/>\n<meta property=\"og:description\" content=\"Si tratta del primo edificio con struttura in legno della Svizzera francese con una facciata fotovoltaica attiva. Il quartiere del Viadotto di Malley \u00e8 contrassegnato dal marchio &quot;Sito 2000 watt&quot; e la nuova estensione di Malley Phare soddisfer\u00e0...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solarchitecture.ch\/it\/malley-phare\/\" \/>\n<meta property=\"og:site_name\" content=\"Solarchitecture\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-08T07:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T09:45:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solar Architecture\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solar Architecture\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/\"},\"author\":{\"name\":\"Solar Architecture\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/#\/schema\/person\/9574b0ccd534aeaa599ef02f64445744\"},\"headline\":\"Malley Phare\",\"datePublished\":\"2024-07-08T07:00:34+00:00\",\"dateModified\":\"2025-02-18T09:45:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/\"},\"wordCount\":1177,\"publisher\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/\",\"url\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/\",\"name\":\"Malley Phare - Solarchitecture\",\"isPartOf\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg\",\"datePublished\":\"2024-07-08T07:00:34+00:00\",\"dateModified\":\"2025-02-18T09:45:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solarchitecture.ch\/it\/malley-phare\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage\",\"url\":\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg\",\"contentUrl\":\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/malley-phare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solarchitecture.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Malley Phare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/#website\",\"url\":\"https:\/\/solarchitecture.ch\/it\/\",\"name\":\"Solarchitecture\",\"description\":\"Building solution\",\"publisher\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solarchitecture.ch\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/#organization\",\"name\":\"Solarchitecture\",\"url\":\"https:\/\/solarchitecture.ch\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2022\/07\/solarchitecture_logo.jpg\",\"contentUrl\":\"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2022\/07\/solarchitecture_logo.jpg\",\"width\":312,\"height\":312,\"caption\":\"Solarchitecture\"},\"image\":{\"@id\":\"https:\/\/solarchitecture.ch\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/#\/schema\/person\/9574b0ccd534aeaa599ef02f64445744\",\"name\":\"Solar Architecture\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/solarchitecture.ch\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5248fcb2bab99263f8f157f166bf6916de4582d008a551554fe906e623e4fda0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5248fcb2bab99263f8f157f166bf6916de4582d008a551554fe906e623e4fda0?s=96&d=mm&r=g\",\"caption\":\"Solar Architecture\"},\"url\":\"https:\/\/solarchitecture.ch\/it\/author\/solar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Malley Phare - Solarchitecture","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solarchitecture.ch\/it\/malley-phare\/","og_locale":"it_IT","og_type":"article","og_title":"Malley Phare - Solarchitecture","og_description":"Si tratta del primo edificio con struttura in legno della Svizzera francese con una facciata fotovoltaica attiva. Il quartiere del Viadotto di Malley \u00e8 contrassegnato dal marchio \"Sito 2000 watt\" e la nuova estensione di Malley Phare soddisfer\u00e0...","og_url":"https:\/\/solarchitecture.ch\/it\/malley-phare\/","og_site_name":"Solarchitecture","article_published_time":"2024-07-08T07:00:34+00:00","article_modified_time":"2025-02-18T09:45:30+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg","type":"image\/jpeg"}],"author":"Solar Architecture","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Solar Architecture","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/#article","isPartOf":{"@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/"},"author":{"name":"Solar Architecture","@id":"https:\/\/solarchitecture.ch\/it\/#\/schema\/person\/9574b0ccd534aeaa599ef02f64445744"},"headline":"Malley Phare","datePublished":"2024-07-08T07:00:34+00:00","dateModified":"2025-02-18T09:45:30+00:00","mainEntityOfPage":{"@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/"},"wordCount":1177,"publisher":{"@id":"https:\/\/solarchitecture.ch\/it\/#organization"},"image":{"@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage"},"thumbnailUrl":"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg","articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/","url":"https:\/\/solarchitecture.ch\/it\/malley-phare\/","name":"Malley Phare - Solarchitecture","isPartOf":{"@id":"https:\/\/solarchitecture.ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage"},"image":{"@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage"},"thumbnailUrl":"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg","datePublished":"2024-07-08T07:00:34+00:00","dateModified":"2025-02-18T09:45:30+00:00","breadcrumb":{"@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solarchitecture.ch\/it\/malley-phare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/#primaryimage","url":"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg","contentUrl":"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2024\/06\/malley-phare_homepage-preview.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/solarchitecture.ch\/it\/malley-phare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solarchitecture.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Malley Phare"}]},{"@type":"WebSite","@id":"https:\/\/solarchitecture.ch\/it\/#website","url":"https:\/\/solarchitecture.ch\/it\/","name":"Solarchitecture","description":"Building solution","publisher":{"@id":"https:\/\/solarchitecture.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solarchitecture.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/solarchitecture.ch\/it\/#organization","name":"Solarchitecture","url":"https:\/\/solarchitecture.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/solarchitecture.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2022\/07\/solarchitecture_logo.jpg","contentUrl":"https:\/\/solarchitecture.ch\/wp-content\/uploads\/2022\/07\/solarchitecture_logo.jpg","width":312,"height":312,"caption":"Solarchitecture"},"image":{"@id":"https:\/\/solarchitecture.ch\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solarchitecture.ch\/it\/#\/schema\/person\/9574b0ccd534aeaa599ef02f64445744","name":"Solar Architecture","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/solarchitecture.ch\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5248fcb2bab99263f8f157f166bf6916de4582d008a551554fe906e623e4fda0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5248fcb2bab99263f8f157f166bf6916de4582d008a551554fe906e623e4fda0?s=96&d=mm&r=g","caption":"Solar Architecture"},"url":"https:\/\/solarchitecture.ch\/it\/author\/solar\/"}]}},"_links":{"self":[{"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/posts\/60045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/users\/2021"}],"replies":[{"embeddable":true,"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/comments?post=60045"}],"version-history":[{"count":30,"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/posts\/60045\/revisions"}],"predecessor-version":[{"id":63857,"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/posts\/60045\/revisions\/63857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/media\/60033"}],"wp:attachment":[{"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/media?parent=60045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/categories?post=60045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solarchitecture.ch\/it\/wp-json\/wp\/v2\/tags?post=60045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}